{"id":751,"date":"2025-03-14T17:05:49","date_gmt":"2025-03-14T17:05:49","guid":{"rendered":"https:\/\/www.fer1956.com\/trasformatori\/"},"modified":"2025-03-25T16:40:13","modified_gmt":"2025-03-25T16:40:13","slug":"transformers","status":"publish","type":"page","link":"https:\/\/www.fer1956.com\/en\/transformers\/","title":{"rendered":"TRANSFORMERS"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;column_reverse&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding_tablet=&#8221;40&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; min_width_desktop=&#8221;60vh&#8221; min_width_tablet=&#8221;50vw&#8221; min_width_phone=&#8221;50vw&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][nectar_highlighted_text style=&#8221;text_outline&#8221; outline_thickness=&#8221;regular&#8221; text_outline_color=&#8221;#000000&#8243; text=&#8221;9vh&#8221; custom_font_size=&#8221;8vh&#8221; text_direction=&#8221;default&#8221;]\n<h1>Transformers<\/h1>\n[\/nectar_highlighted_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding_tablet=&#8221;0px&#8221; top_padding_phone=&#8221;0px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; min_width_tablet=&#8221;0px&#8221; min_width_phone=&#8221;0px&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;padding-9-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]We design and manufacture transformers with power ratings ranging from a few tenths of a Watt to approximately 3kW. We have winding processes available for various types of wire, including Litz, capillary wires with a section of 0.002mm\u00b2, up to enamelled copper wires up to 14mm\u00b2.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;568&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;ro-reveal-from-left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;20px&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;125%&#8221; max_width_mobile=&#8221;125%&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;8%&#8221; right_padding_desktop=&#8221;8%&#8221; top_padding_tablet=&#8221;10%&#8221; bottom_padding_tablet=&#8221;15%&#8221; left_padding_tablet=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;hidden&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#000000&#8243; shape_divider_position=&#8221;top&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;3&#8243; desktop_small_cols_flickity=&#8221;3&#8243; tablet_cols_flickity=&#8221;2&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;touch_total&#8221; flickity_touch_total_style=&#8221;solid_bg&#8221; flickity_touch_total_indicator_bg_color=&#8221;#27327c&#8221; flickity_touch_total_indicator_icon_color=&#8221;#ffffff&#8221; flickity_touch_total_hide_indicator=&#8221;true&#8221; color=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; flickity_spacing=&#8221;15px&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;0&#8243; flickity_image_scale_on_drag=&#8221;true&#8221; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1742920750856-1&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1742920750856-0&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;586&#8243; image_aspect_ratio=&#8221;1-1&#8243; content_color=&#8221;#000000&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; image_size=&#8221;large&#8221;]\n<h4>Single-phase and three-phase, toroidal and laminated electrical transformers<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1742920750893-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1742920750894-4&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;589&#8243; image_aspect_ratio=&#8221;1-1&#8243; content_color=&#8221;#000000&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; image_size=&#8221;large&#8221;]\n<h4>Transformers and inductors with ferrite cores<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1742920750918-6&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1742920750918-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;588&#8243; image_aspect_ratio=&#8221;1-1&#8243; content_color=&#8221;#000000&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; image_size=&#8221;large&#8221;]\n<h4>Isolation transformers<\/h4>\n[\/fancy_box][\/item][\/carousel][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;column_reverse&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":752,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-751","page","type-page","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.fer1956.com\/en\/wp-json\/wp\/v2\/pages\/751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fer1956.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fer1956.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fer1956.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fer1956.com\/en\/wp-json\/wp\/v2\/comments?post=751"}],"version-history":[{"count":3,"href":"https:\/\/www.fer1956.com\/en\/wp-json\/wp\/v2\/pages\/751\/revisions"}],"predecessor-version":[{"id":879,"href":"https:\/\/www.fer1956.com\/en\/wp-json\/wp\/v2\/pages\/751\/revisions\/879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fer1956.com\/en\/wp-json\/wp\/v2\/media\/752"}],"wp:attachment":[{"href":"https:\/\/www.fer1956.com\/en\/wp-json\/wp\/v2\/media?parent=751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}